{"id":18399,"date":"2024-11-21T11:21:05","date_gmt":"2024-11-21T10:21:05","guid":{"rendered":"https:\/\/onezone.ch\/?page_id=18399"},"modified":"2025-04-04T18:31:07","modified_gmt":"2025-04-04T16:31:07","slug":"onezone-gutschein-20","status":"publish","type":"page","link":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/","title":{"rendered":"onezone gutschein 20"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18399\" class=\"elementor elementor-18399\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4608aa9 e-flex e-con-boxed e-con e-parent\" data-id=\"4608aa9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbfbd5a elementor-widget elementor-widget-image\" data-id=\"bbfbd5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg\" class=\"attachment-large size-large wp-image-1284\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b44e650 e-flex e-con-boxed e-con e-parent\" data-id=\"b44e650\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49cb765 elementor-widget elementor-widget-heading\" data-id=\"49cb765\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">All deine Versicherungen im \u00dcberblick <br>und 20CHF Gutschein sichern<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3387a41 e-flex e-con-boxed e-con e-child\" data-id=\"3387a41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c32c2f elementor-widget elementor-widget-text-editor\" data-id=\"2c32c2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Spare<\/strong>\u00a0<strong>Zeit<\/strong>\u00a0und\u00a0<strong>Aufwand<\/strong>! Mit unserer neuen\u00a0<strong>App oneZone<\/strong>\u00a0wird die Verwaltung deiner Versicherungspolicen\u00a0<strong>revolutioniert:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ac2c35 e-con-full e-flex e-con e-child\" data-id=\"9ac2c35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c409e51 elementor-widget elementor-widget-button\" data-id=\"c409e51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#wie\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wie funkzionierts?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-779f18f elementor-widget elementor-widget-button\" data-id=\"779f18f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/webapp.onezone.ch\/#\/home\/register\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt anmelden und gutschein sichern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8490613 e-con-full e-flex e-con e-child\" data-id=\"8490613\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13f19ae elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"13f19ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"622\" height=\"400\" src=\"https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/gutschein-back-onezone.png\" class=\"attachment-large size-large wp-image-18428\" alt=\"\" srcset=\"https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/gutschein-back-onezone.png 622w, https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/gutschein-back-onezone-600x386.png 600w\" sizes=\"(max-width: 622px) 100vw, 622px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caaf355 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"caaf355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/smartphone-app-onezone.png\" class=\"attachment-large size-large wp-image-18253\" alt=\"\" srcset=\"https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/smartphone-app-onezone.png 600w, https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/smartphone-app-onezone-480x480.png 480w, https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/smartphone-app-onezone-800x800.png 800w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-797affa e-flex e-con-boxed e-con e-parent\" data-id=\"797affa\" data-element_type=\"container\" data-e-type=\"container\" id=\"wie\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d110c38 elementor-widget elementor-widget-heading\" data-id=\"d110c38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kostenlos und einfach <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55157d3 elementor-widget elementor-widget-text-editor\" data-id=\"55157d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Eingabe hier...\"><span style=\"color: #000000;\">So kannst du unsere Onezone App nutzen und dir den gutschein von 20CHF sichern<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f469e3b elementor-widget elementor-widget-text-editor\" data-id=\"f469e3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Es ist ganz einfach:<\/strong><\/span> <span style=\"color: #333333;\">Melde dich bei <strong>OneZone<\/strong> an, w\u00e4hle 2 bestehende Versicherungen (ohne gesetzliche Krankenkassen) aus und unterschreibe das Mandat, um deinen <strong>20 CHF Gutschein von Brack.ch<\/strong> zu erhalten. Der Gutschein wird dir ausgestellt, sobald deine Versicherungsvertr\u00e4ge best\u00e4tigt wurden.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33f7fa6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"33f7fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt anfangen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f31b648 elementor-widget elementor-widget-image\" data-id=\"f31b648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"622\" src=\"https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/onezone-registrierung-tutorial-1.png\" class=\"attachment-large size-large wp-image-18436\" alt=\"\" srcset=\"https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/onezone-registrierung-tutorial-1.png 1200w, https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/onezone-registrierung-tutorial-1-600x311.png 600w, https:\/\/onezone.ch\/wp-content\/uploads\/2024\/11\/onezone-registrierung-tutorial-1-768x398.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9fd65da e-flex e-con-boxed e-con e-parent\" data-id=\"9fd65da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>All deine Versicherungen im \u00dcberblick und 20CHF Gutschein sichern Spare\u00a0Zeit\u00a0und\u00a0Aufwand!&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18399","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.6 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>onezone gutschein 20 - Versicherungs app - digitaler Versicherungsbroker Schweiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"onezone gutschein 20\" \/>\n<meta property=\"og:description\" content=\"All deine Versicherungen im \u00dcberblick und 20CHF Gutschein sichern Spare\u00a0Zeit\u00a0und\u00a0Aufwand!...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Versicherungs app - digitaler Versicherungsbroker Schweiz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/onezone.ch\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-04T16:31:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/09\/fb-bild-oneZone.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/\",\"url\":\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/\",\"name\":\"onezone gutschein 20 - Versicherungs app - digitaler Versicherungsbroker Schweiz\",\"isPartOf\":{\"@id\":\"https:\/\/onezone.ch\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg\",\"datePublished\":\"2024-11-21T10:21:05+00:00\",\"dateModified\":\"2025-04-04T16:31:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#primaryimage\",\"url\":\"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg\",\"contentUrl\":\"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/onezone.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"onezone gutschein 20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/onezone.ch\/it\/#website\",\"url\":\"https:\/\/onezone.ch\/it\/\",\"name\":\"Versicherungs app - Versicherungsbroker Schweiz\",\"description\":\"versicherungs app, digitaler versicherungsmakler schweiz, autoversicherung, lebensversicherung, s\u00e4ule 3a, rechtsschutzversicherung, krankenkasse, reiseversicherung, mietkautionsversicherung, tierversicherung, hausratversicherung, privathaftpflicht versicherung, versicherungsbroker\",\"publisher\":{\"@id\":\"https:\/\/onezone.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/onezone.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/onezone.ch\/it\/#organization\",\"name\":\"oneZone Versicherung Schweiz\",\"url\":\"https:\/\/onezone.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/onezone.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg\",\"contentUrl\":\"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg\",\"width\":1,\"height\":1,\"caption\":\"oneZone Versicherung Schweiz\"},\"image\":{\"@id\":\"https:\/\/onezone.ch\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/onezone.ch\/\",\"https:\/\/www.instagram.com\/oneZone.ch\/\",\"https:\/\/www.youtube.com\/channel\/UCkADqFvOChofZlL-UkA85mg\/featured\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"onezone gutschein 20 - Versicherungs app - digitaler Versicherungsbroker Schweiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/","og_locale":"it_IT","og_type":"article","og_title":"onezone gutschein 20","og_description":"All deine Versicherungen im \u00dcberblick und 20CHF Gutschein sichern Spare\u00a0Zeit\u00a0und\u00a0Aufwand!...","og_url":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/","og_site_name":"Versicherungs app - digitaler Versicherungsbroker Schweiz","article_publisher":"https:\/\/www.facebook.com\/onezone.ch\/","article_modified_time":"2025-04-04T16:31:07+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/09\/fb-bild-oneZone.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/","url":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/","name":"onezone gutschein 20 - Versicherungs app - digitaler Versicherungsbroker Schweiz","isPartOf":{"@id":"https:\/\/onezone.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#primaryimage"},"image":{"@id":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#primaryimage"},"thumbnailUrl":"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg","datePublished":"2024-11-21T10:21:05+00:00","dateModified":"2025-04-04T16:31:07+00:00","breadcrumb":{"@id":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onezone.ch\/it\/onezone-gutschein-20\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#primaryimage","url":"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg","contentUrl":"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/onezone.ch\/it\/onezone-gutschein-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onezone.ch\/it\/"},{"@type":"ListItem","position":2,"name":"onezone gutschein 20"}]},{"@type":"WebSite","@id":"https:\/\/onezone.ch\/it\/#website","url":"https:\/\/onezone.ch\/it\/","name":"Versicherungs app - Versicherungsbroker Schweiz","description":"versicherungs app, digitaler versicherungsmakler schweiz, autoversicherung, lebensversicherung, s\u00e4ule 3a, rechtsschutzversicherung, krankenkasse, reiseversicherung, mietkautionsversicherung, tierversicherung, hausratversicherung, privathaftpflicht versicherung, versicherungsbroker","publisher":{"@id":"https:\/\/onezone.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onezone.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/onezone.ch\/it\/#organization","name":"oneZone Versicherung Schweiz","url":"https:\/\/onezone.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/onezone.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg","contentUrl":"https:\/\/onezone.ch\/wp-content\/uploads\/2022\/07\/onezone-logo-pos-RGB.svg","width":1,"height":1,"caption":"oneZone Versicherung Schweiz"},"image":{"@id":"https:\/\/onezone.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/onezone.ch\/","https:\/\/www.instagram.com\/oneZone.ch\/","https:\/\/www.youtube.com\/channel\/UCkADqFvOChofZlL-UkA85mg\/featured"]}]}},"_links":{"self":[{"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/pages\/18399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/comments?post=18399"}],"version-history":[{"count":50,"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/pages\/18399\/revisions"}],"predecessor-version":[{"id":21076,"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/pages\/18399\/revisions\/21076"}],"wp:attachment":[{"href":"https:\/\/onezone.ch\/it\/wp-json\/wp\/v2\/media?parent=18399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}